{"id":3501,"date":"2022-11-24T11:19:49","date_gmt":"2022-11-24T10:19:49","guid":{"rendered":"https:\/\/www.domainedesbarons.com\/le-jardin-medieval-duzes-et-ses-tours-idees-pour-2023\/"},"modified":"2023-04-17T16:22:03","modified_gmt":"2023-04-17T14:22:03","slug":"le-jardin-medieval-duzes-et-ses-tours-idees-pour-2023","status":"publish","type":"post","link":"https:\/\/www.domainedesbarons.com\/en\/le-jardin-medieval-duzes-et-ses-tours-idees-pour-2023\/","title":{"rendered":"The medieval garden of Uz\u00e8s and its towers. Ideas for 2023"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false},"categories":[30],"tags":[],"class_list":["post-3501","post","type-post","status-publish","format-standard","hentry","category-activities-and-visits"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>The medieval garden of Uz\u00e8s and its towers. Ideas for 2023 - Domaine des Barons de la Chasse<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.domainedesbarons.com\/en\/le-jardin-medieval-duzes-et-ses-tours-idees-pour-2023\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The medieval garden of Uz\u00e8s and its towers. Ideas for 2023 - Domaine des Barons de la Chasse\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.domainedesbarons.com\/en\/le-jardin-medieval-duzes-et-ses-tours-idees-pour-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Domaine des Barons de la Chasse\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/domainedesbaronsdelachasse\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-24T10:19:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-17T14:22:03+00:00\" \/>\n<meta name=\"author\" content=\"Angela Zimmer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Angela Zimmer\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.domainedesbarons.com\/en\/le-jardin-medieval-duzes-et-ses-tours-idees-pour-2023\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.domainedesbarons.com\/en\/le-jardin-medieval-duzes-et-ses-tours-idees-pour-2023\/\"},\"author\":{\"name\":\"Angela Zimmer\",\"@id\":\"https:\/\/www.domainedesbarons.com\/en\/#\/schema\/person\/51ff269eeb8b2ff213fcf4d0ac96b4ee\"},\"headline\":\"The medieval garden of Uz\u00e8s and its towers. Ideas for 2023\",\"datePublished\":\"2022-11-24T10:19:49+00:00\",\"dateModified\":\"2023-04-17T14:22:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.domainedesbarons.com\/en\/le-jardin-medieval-duzes-et-ses-tours-idees-pour-2023\/\"},\"wordCount\":11,\"publisher\":{\"@id\":\"https:\/\/www.domainedesbarons.com\/en\/#organization\"},\"articleSection\":[\"Activities &amp; visits\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.domainedesbarons.com\/en\/le-jardin-medieval-duzes-et-ses-tours-idees-pour-2023\/\",\"url\":\"https:\/\/www.domainedesbarons.com\/en\/le-jardin-medieval-duzes-et-ses-tours-idees-pour-2023\/\",\"name\":\"The medieval garden of Uz\u00e8s and its towers. Ideas for 2023 - Domaine des Barons de la Chasse\",\"isPartOf\":{\"@id\":\"https:\/\/www.domainedesbarons.com\/en\/#website\"},\"datePublished\":\"2022-11-24T10:19:49+00:00\",\"dateModified\":\"2023-04-17T14:22:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.domainedesbarons.com\/en\/le-jardin-medieval-duzes-et-ses-tours-idees-pour-2023\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.domainedesbarons.com\/en\/le-jardin-medieval-duzes-et-ses-tours-idees-pour-2023\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.domainedesbarons.com\/en\/le-jardin-medieval-duzes-et-ses-tours-idees-pour-2023\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.domainedesbarons.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The medieval garden of Uz\u00e8s and its towers. Ideas for 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.domainedesbarons.com\/en\/#website\",\"url\":\"https:\/\/www.domainedesbarons.com\/en\/\",\"name\":\"Domaine des Barons de la Chasse\",\"description\":\"\u00c9co-Domaine R\u00e9sidentiel\",\"publisher\":{\"@id\":\"https:\/\/www.domainedesbarons.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.domainedesbarons.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.domainedesbarons.com\/en\/#organization\",\"name\":\"Domaine des Barons de la Chasse\",\"url\":\"https:\/\/www.domainedesbarons.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.domainedesbarons.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.domainedesbarons.com\/wp-content\/uploads\/2020\/07\/Logo-DBC-2.svg\",\"contentUrl\":\"https:\/\/www.domainedesbarons.com\/wp-content\/uploads\/2020\/07\/Logo-DBC-2.svg\",\"caption\":\"Domaine des Barons de la Chasse\"},\"image\":{\"@id\":\"https:\/\/www.domainedesbarons.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/domainedesbaronsdelachasse\/\",\"https:\/\/www.instagram.com\/domainedesbaronsdelachasse\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.domainedesbarons.com\/en\/#\/schema\/person\/51ff269eeb8b2ff213fcf4d0ac96b4ee\",\"name\":\"Angela Zimmer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.domainedesbarons.com\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f729eb894151f91cbff46ef8059e90e69eea41326454283ca4d0adebcf7f163a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f729eb894151f91cbff46ef8059e90e69eea41326454283ca4d0adebcf7f163a?s=96&d=mm&r=g\",\"caption\":\"Angela Zimmer\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The medieval garden of Uz\u00e8s and its towers. Ideas for 2023 - Domaine des Barons de la Chasse","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.domainedesbarons.com\/en\/le-jardin-medieval-duzes-et-ses-tours-idees-pour-2023\/","og_locale":"en_US","og_type":"article","og_title":"The medieval garden of Uz\u00e8s and its towers. Ideas for 2023 - Domaine des Barons de la Chasse","og_url":"https:\/\/www.domainedesbarons.com\/en\/le-jardin-medieval-duzes-et-ses-tours-idees-pour-2023\/","og_site_name":"Domaine des Barons de la Chasse","article_publisher":"https:\/\/www.facebook.com\/domainedesbaronsdelachasse\/","article_published_time":"2022-11-24T10:19:49+00:00","article_modified_time":"2023-04-17T14:22:03+00:00","author":"Angela Zimmer","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Angela Zimmer"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.domainedesbarons.com\/en\/le-jardin-medieval-duzes-et-ses-tours-idees-pour-2023\/#article","isPartOf":{"@id":"https:\/\/www.domainedesbarons.com\/en\/le-jardin-medieval-duzes-et-ses-tours-idees-pour-2023\/"},"author":{"name":"Angela Zimmer","@id":"https:\/\/www.domainedesbarons.com\/en\/#\/schema\/person\/51ff269eeb8b2ff213fcf4d0ac96b4ee"},"headline":"The medieval garden of Uz\u00e8s and its towers. Ideas for 2023","datePublished":"2022-11-24T10:19:49+00:00","dateModified":"2023-04-17T14:22:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.domainedesbarons.com\/en\/le-jardin-medieval-duzes-et-ses-tours-idees-pour-2023\/"},"wordCount":11,"publisher":{"@id":"https:\/\/www.domainedesbarons.com\/en\/#organization"},"articleSection":["Activities &amp; visits"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.domainedesbarons.com\/en\/le-jardin-medieval-duzes-et-ses-tours-idees-pour-2023\/","url":"https:\/\/www.domainedesbarons.com\/en\/le-jardin-medieval-duzes-et-ses-tours-idees-pour-2023\/","name":"The medieval garden of Uz\u00e8s and its towers. Ideas for 2023 - Domaine des Barons de la Chasse","isPartOf":{"@id":"https:\/\/www.domainedesbarons.com\/en\/#website"},"datePublished":"2022-11-24T10:19:49+00:00","dateModified":"2023-04-17T14:22:03+00:00","breadcrumb":{"@id":"https:\/\/www.domainedesbarons.com\/en\/le-jardin-medieval-duzes-et-ses-tours-idees-pour-2023\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.domainedesbarons.com\/en\/le-jardin-medieval-duzes-et-ses-tours-idees-pour-2023\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.domainedesbarons.com\/en\/le-jardin-medieval-duzes-et-ses-tours-idees-pour-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.domainedesbarons.com\/en\/"},{"@type":"ListItem","position":2,"name":"The medieval garden of Uz\u00e8s and its towers. Ideas for 2023"}]},{"@type":"WebSite","@id":"https:\/\/www.domainedesbarons.com\/en\/#website","url":"https:\/\/www.domainedesbarons.com\/en\/","name":"Domaine des Barons de la Chasse","description":"\u00c9co-Domaine R\u00e9sidentiel","publisher":{"@id":"https:\/\/www.domainedesbarons.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.domainedesbarons.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.domainedesbarons.com\/en\/#organization","name":"Domaine des Barons de la Chasse","url":"https:\/\/www.domainedesbarons.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.domainedesbarons.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.domainedesbarons.com\/wp-content\/uploads\/2020\/07\/Logo-DBC-2.svg","contentUrl":"https:\/\/www.domainedesbarons.com\/wp-content\/uploads\/2020\/07\/Logo-DBC-2.svg","caption":"Domaine des Barons de la Chasse"},"image":{"@id":"https:\/\/www.domainedesbarons.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/domainedesbaronsdelachasse\/","https:\/\/www.instagram.com\/domainedesbaronsdelachasse\/"]},{"@type":"Person","@id":"https:\/\/www.domainedesbarons.com\/en\/#\/schema\/person\/51ff269eeb8b2ff213fcf4d0ac96b4ee","name":"Angela Zimmer","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.domainedesbarons.com\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f729eb894151f91cbff46ef8059e90e69eea41326454283ca4d0adebcf7f163a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f729eb894151f91cbff46ef8059e90e69eea41326454283ca4d0adebcf7f163a?s=96&d=mm&r=g","caption":"Angela Zimmer"}}]}},"_links":{"self":[{"href":"https:\/\/www.domainedesbarons.com\/en\/wp-json\/wp\/v2\/posts\/3501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.domainedesbarons.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.domainedesbarons.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.domainedesbarons.com\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.domainedesbarons.com\/en\/wp-json\/wp\/v2\/comments?post=3501"}],"version-history":[{"count":5,"href":"https:\/\/www.domainedesbarons.com\/en\/wp-json\/wp\/v2\/posts\/3501\/revisions"}],"predecessor-version":[{"id":3725,"href":"https:\/\/www.domainedesbarons.com\/en\/wp-json\/wp\/v2\/posts\/3501\/revisions\/3725"}],"wp:attachment":[{"href":"https:\/\/www.domainedesbarons.com\/en\/wp-json\/wp\/v2\/media?parent=3501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.domainedesbarons.com\/en\/wp-json\/wp\/v2\/categories?post=3501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.domainedesbarons.com\/en\/wp-json\/wp\/v2\/tags?post=3501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}